{"id":8623,"date":"2021-08-10T10:58:17","date_gmt":"2021-08-10T08:58:17","guid":{"rendered":"https:\/\/www.forpol.es\/obras-realizadas\/precomur\/"},"modified":"2022-12-06T06:39:47","modified_gmt":"2022-12-06T04:39:47","slug":"precomur","status":"publish","type":"obras-realizadas","link":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/","title":{"rendered":"Precomur"},"content":{"rendered":"<h2 id=\"cc-m-header-11177272998\">HABITATGE AMB PRELOSA FARLAP I MURS DE FORMIG\u00d3 A SANTA EUL\u00c0LIA DE PUIG-ORIOL<\/h2>\n<h3>CONSTRUCCI\u00d3 DE FORJATS AMB PRELOSES I MURS DE FORMIG\u00d3 PRECOMUR.<\/h3>\n<p>Prelosa FARLAP I PRECOMUR:<\/p>\n<ul>\n<li>TERMACOL 3 + 21 per a forjat de 29 cm de gruix. 138,05 m \u00b2<\/li>\n<li>TERMACOL 3 + 26 per a forjat de 34 cm de gruix. 67,72 m \u00b2<\/li>\n<li>FARLAP II F-22-2 per a forjat de 30 cm de gruix. 138,05 m \u00b2<\/li>\n<li>Plaques Mur Prefabricat de 0.30 x 1: 20 73,50 m \u00b2<\/li>\n<\/ul>\n<h3><strong>MUR PREFABRICAT PRECOMUR:<\/strong><\/h3>\n<ul>\n<li>Mur prefabricat, constitu\u00eft per dues llasses de 5 cm paral\u00b7, els gruixos del mur estan en funci\u00f3 de les c\u00e0rregues i longituds descrites a continuaci\u00f3.<\/li>\n<li>Amb bisell exterior o juntes cada 1.2 m verticalment.<\/li>\n<li>Formig\u00f3 HA-25 a les cares del prefabricat, acer B-500-S, a l&#8217; interior del prefabricat.<\/li>\n<li>En el cas de realitzar el c\u00e0lcul de fonamentaci\u00f3 i mur pel departament t\u00e8cnic de FORPOL ESTRUCTURAS, S.L. aquest s&#8217; ajustar\u00e0 a la norma EHE, EFHE, Euro codi, NT d&#8217; estructures i bibliografia del professor J. Calavera.<\/li>\n<li>Toler\u00e0ncia en qualsevol de les dimensions de les plaques + &#8211; 2 cm.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4><strong>PLACA FARLAP:&nbsp;<\/strong><\/h4>\n<ul>\n<li>Placa autoportant per a sostre calculada en funci\u00f3 de les c\u00e0rregues i longituds descrites a continuaci\u00f3.<\/li>\n<li>Es compon duna llosa inferior de 4cm quatre nervis pretesats amb revolt\u00f3 de poliestir\u00e8 incloses entre els nervis.<\/li>\n<li>Formig\u00f3 HP-45\/P\/12\/IIa resist\u00e8ncia caracter\u00edstica 45 N\/mm2, acer pretensat I 1860 C E1 de resist\u00e8ncia caracter\u00edstica 1.658 N\/mm2. (Que s&#8217;han de complementar amb la col\u00b7locaci\u00f3 de negatius segons pl\u00e0nol d&#8217;execuci\u00f3 i una xapa de formig\u00f3 H-25 \/ B \/ 16 \/ IIa de 5 cm.<\/li>\n<li>De gruix amb la seva malla de repartiment a c\u00e0rrec de la propietat .) plaques posades en obra sobre cami\u00f3.<\/li>\n<li>Toler\u00e0ncia dimensional de les plaques \u00b1 2cm. (precomur)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4><strong>TERMACOL ARMADA:<\/strong><\/h4>\n<ul>\n<li>Placa autoportant per a sostre calculada en funci\u00f3 de les c\u00e0rregues i longituds descrites a continuaci\u00f3.<\/li>\n<li>Composta de dos nervis de formig\u00f3 armat de doble t\u00e9, amb un entre eix de 60 cm, units mitjan\u00e7ant panells de poliestir\u00e8 expandit continu (sense pont t\u00e8rmic).<\/li>\n<li>Formig\u00f3 HA-25 \/ P \/ 16IIa resist\u00e8ncia caracter\u00edstica 25 N \/ mm2.<\/li>\n<li>Acer B-500S de resist\u00e8ncia caracter\u00edstica 500 N \/ mm2. (Que s&#8217;han de complementar amb la col\u00b7locaci\u00f3 de negatius segons pl\u00e0nol d&#8217;execuci\u00f3 i una xapa de formig\u00f3 H250 de 5 cm de gruix amb la seva malla de repartiment a c\u00e0rrec de la propietat.). Plaques posades en obra sobre cami\u00f3 .toler\u00e0ncia dimensional de les plaques + &#8211; 2 cm. (precomur)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Adre\u00e7a:&nbsp;C\/ Pla de la Bassa &#8211;&nbsp;08514 Santa Eul\u00e0lia de Puig-Oriol,Barcelona&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HABITATGE AMB PRELOSA FARLAP I MURS DE FORMIG\u00d3<br \/>\nConstrucci\u00f3 de murs prefabricats PRECOMUR a Barcelona<br \/>\nForpol Estructures empresa l\u00edder en murs prefabricats de formig\u00f3 armat<\/p>\n","protected":false},"featured_media":7293,"template":"","tipo":[76],"class_list":["post-8623","obras-realizadas","type-obras-realizadas","status-publish","has-post-thumbnail","hentry","tipo-prefabricats-de-formigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.12 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PRECOMUR mur de formig\u00f3 - Forpol Estructuras, S.L. 2026<\/title>\n<meta name=\"description\" content=\"Construcci\u00f3 de murs prefabricats PRECOMUR a Barcelona - Forpol Estructures empresa l\u00edder en murs prefabricats de formig\u00f3 armat\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Precomur\" \/>\n<meta property=\"og:description\" content=\"Construcci\u00f3 de murs prefabricats PRECOMUR a Barcelona - Forpol Estructures empresa l\u00edder en murs prefabricats de formig\u00f3 armat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/\" \/>\n<meta property=\"og:site_name\" content=\"Forpol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forpolestructuras\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-06T04:39:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forpol.es\/wp-content\/uploads\/2021\/08\/OK-FORJADO-Y-MURO-EN-SANTA-EULALIA-DE-PUIG-ORIOL-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@forpol2\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuts\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PRECOMUR mur de formig\u00f3 - Forpol Estructuras, S.L. 2026","description":"Construcci\u00f3 de murs prefabricats PRECOMUR a Barcelona - Forpol Estructures empresa l\u00edder en murs prefabricats de formig\u00f3 armat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/","og_locale":"ca_ES","og_type":"article","og_title":"Precomur","og_description":"Construcci\u00f3 de murs prefabricats PRECOMUR a Barcelona - Forpol Estructures empresa l\u00edder en murs prefabricats de formig\u00f3 armat","og_url":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/","og_site_name":"Forpol","article_publisher":"https:\/\/www.facebook.com\/forpolestructuras\/","article_modified_time":"2022-12-06T04:39:47+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.forpol.es\/wp-content\/uploads\/2021\/08\/OK-FORJADO-Y-MURO-EN-SANTA-EULALIA-DE-PUIG-ORIOL-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@forpol2","twitter_misc":{"Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/","url":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/","name":"PRECOMUR mur de formig\u00f3 - Forpol Estructuras, S.L. 2026","isPartOf":{"@id":"https:\/\/www.forpol.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/#primaryimage"},"image":{"@id":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forpol.es\/wp-content\/uploads\/2021\/08\/OK-FORJADO-Y-MURO-EN-SANTA-EULALIA-DE-PUIG-ORIOL-3.jpg","datePublished":"2021-08-10T08:58:17+00:00","dateModified":"2022-12-06T04:39:47+00:00","description":"Construcci\u00f3 de murs prefabricats PRECOMUR a Barcelona - Forpol Estructures empresa l\u00edder en murs prefabricats de formig\u00f3 armat","breadcrumb":{"@id":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/#primaryimage","url":"https:\/\/www.forpol.es\/wp-content\/uploads\/2021\/08\/OK-FORJADO-Y-MURO-EN-SANTA-EULALIA-DE-PUIG-ORIOL-3.jpg","contentUrl":"https:\/\/www.forpol.es\/wp-content\/uploads\/2021\/08\/OK-FORJADO-Y-MURO-EN-SANTA-EULALIA-DE-PUIG-ORIOL-3.jpg","width":1600,"height":1200,"caption":"FORJAT I MUR A SANTA EUL\u00c0LIA DE PUIG-ORIOL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.forpol.es\/ca\/obras-realizadas\/precomur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.forpol.es\/ca\/inici\/"},{"@type":"ListItem","position":2,"name":"Precomur"}]},{"@type":"WebSite","@id":"https:\/\/www.forpol.es\/ca\/#website","url":"https:\/\/www.forpol.es\/ca\/","name":"Forpol","description":"Prefabricats de formig\u00f3 i estructures prefabricades","publisher":{"@id":"https:\/\/www.forpol.es\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forpol.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.forpol.es\/ca\/#organization","name":"Forpol Estructuras, S.L.","alternateName":"Forpol","url":"https:\/\/www.forpol.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.forpol.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.forpol.es\/wp-content\/uploads\/2021\/09\/LOGO-PNG-200x75-2-e1632825250267.png","contentUrl":"https:\/\/www.forpol.es\/wp-content\/uploads\/2021\/09\/LOGO-PNG-200x75-2-e1632825250267.png","width":90,"height":34,"caption":"Forpol Estructuras, S.L."},"image":{"@id":"https:\/\/www.forpol.es\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forpolestructuras\/","https:\/\/x.com\/forpol2","https:\/\/www.instagram.com\/forpol_estructuras\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.forpol.es\/ca\/wp-json\/wp\/v2\/obras-realizadas\/8623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forpol.es\/ca\/wp-json\/wp\/v2\/obras-realizadas"}],"about":[{"href":"https:\/\/www.forpol.es\/ca\/wp-json\/wp\/v2\/types\/obras-realizadas"}],"version-history":[{"count":0,"href":"https:\/\/www.forpol.es\/ca\/wp-json\/wp\/v2\/obras-realizadas\/8623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forpol.es\/ca\/wp-json\/wp\/v2\/media\/7293"}],"wp:attachment":[{"href":"https:\/\/www.forpol.es\/ca\/wp-json\/wp\/v2\/media?parent=8623"}],"wp:term":[{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.forpol.es\/ca\/wp-json\/wp\/v2\/tipo?post=8623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}